{"id":269,"count":1,"description":"","link":"https:\/\/curatingla.com\/cla\/tag\/kinetic-art\/","name":"Kinetic Art","slug":"kinetic-art","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kinetic Art Archives - Curating Los Angeles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/curatingla.com\/cla\/tag\/kinetic-art\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kinetic Art Archives - Curating Los Angeles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/curatingla.com\/cla\/tag\/kinetic-art\/\" \/>\n<meta property=\"og:site_name\" content=\"Curating Los Angeles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CuratingLA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/curatingla.com\\\/cla\\\/tag\\\/kinetic-art\\\/\",\"url\":\"https:\\\/\\\/curatingla.com\\\/cla\\\/tag\\\/kinetic-art\\\/\",\"name\":\"Kinetic Art Archives - Curating Los Angeles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/curatingla.com\\\/cla\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/curatingla.com\\\/cla\\\/tag\\\/kinetic-art\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/curatingla.com\\\/cla\\\/tag\\\/kinetic-art\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/curatingla.com\\\/cla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kinetic Art\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/curatingla.com\\\/cla\\\/#website\",\"url\":\"https:\\\/\\\/curatingla.com\\\/cla\\\/\",\"name\":\"Curating Los Angeles\",\"description\":\"Exploring the people, places &amp; culture of greater LA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/curatingla.com\\\/cla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kinetic Art Archives - Curating Los Angeles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/curatingla.com\/cla\/tag\/kinetic-art\/","og_locale":"en_US","og_type":"article","og_title":"Kinetic Art Archives - Curating Los Angeles","og_url":"https:\/\/curatingla.com\/cla\/tag\/kinetic-art\/","og_site_name":"Curating Los Angeles","twitter_card":"summary_large_image","twitter_site":"@CuratingLA","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/curatingla.com\/cla\/tag\/kinetic-art\/","url":"https:\/\/curatingla.com\/cla\/tag\/kinetic-art\/","name":"Kinetic Art Archives - Curating Los Angeles","isPartOf":{"@id":"https:\/\/curatingla.com\/cla\/#website"},"breadcrumb":{"@id":"https:\/\/curatingla.com\/cla\/tag\/kinetic-art\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/curatingla.com\/cla\/tag\/kinetic-art\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/curatingla.com\/cla\/"},{"@type":"ListItem","position":2,"name":"Kinetic Art"}]},{"@type":"WebSite","@id":"https:\/\/curatingla.com\/cla\/#website","url":"https:\/\/curatingla.com\/cla\/","name":"Curating Los Angeles","description":"Exploring the people, places &amp; culture of greater LA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/curatingla.com\/cla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/curatingla.com\/cla\/wp-json\/wp\/v2\/tags\/269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/curatingla.com\/cla\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/curatingla.com\/cla\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/curatingla.com\/cla\/wp-json\/wp\/v2\/posts?tags=269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}